{"id":5653,"date":"2026-05-12T14:01:51","date_gmt":"2026-05-12T14:01:51","guid":{"rendered":"https:\/\/www.immopeople.be\/?post_type=a-vendre&#038;p=5653"},"modified":"2026-05-12T14:01:51","modified_gmt":"2026-05-12T14:01:51","slug":"quartier-louise-penthouse-contemporain-avec-2-terrasses","status":"publish","type":"a-vendre","link":"https:\/\/www.immopeople.be\/nl\/a-vendre\/quartier-louise-penthouse-contemporain-avec-2-terrasses\/","title":{"rendered":"Quartier Louise &#8211; Penthouse contemporain avec 2 terrasses"},"featured_media":5660,"template":"","categorie-biens":[40,6],"class_list":["post-5653","a-vendre","type-a-vendre","status-publish","has-post-thumbnail","hentry","categorie-biens-a-vendre","categorie-biens-appartement"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Quartier Louise - Penthouse contemporain avec 2 terrasses - Immo People<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.immopeople.be\/nl\/a-vendre\/quartier-louise-penthouse-contemporain-avec-2-terrasses\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quartier Louise - Penthouse contemporain avec 2 terrasses - Immo People\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.immopeople.be\/nl\/a-vendre\/quartier-louise-penthouse-contemporain-avec-2-terrasses\/\" \/>\n<meta property=\"og:site_name\" content=\"Immo People\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100091200924603&amp;locale=fr_FR\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.immopeople.be\/wp-content\/uploads\/2026\/05\/image00010-3.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.immopeople.be\/nl\/a-vendre\/quartier-louise-penthouse-contemporain-avec-2-terrasses\/\",\"url\":\"https:\/\/www.immopeople.be\/nl\/a-vendre\/quartier-louise-penthouse-contemporain-avec-2-terrasses\/\",\"name\":\"Quartier Louise - Penthouse contemporain avec 2 terrasses - Immo People\",\"isPartOf\":{\"@id\":\"https:\/\/www.immopeople.be\/nl\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.immopeople.be\/nl\/a-vendre\/quartier-louise-penthouse-contemporain-avec-2-terrasses\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.immopeople.be\/nl\/a-vendre\/quartier-louise-penthouse-contemporain-avec-2-terrasses\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.immopeople.be\/wp-content\/uploads\/2026\/05\/image00010-3.jpeg\",\"datePublished\":\"2026-05-12T14:01:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.immopeople.be\/nl\/a-vendre\/quartier-louise-penthouse-contemporain-avec-2-terrasses\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.immopeople.be\/nl\/a-vendre\/quartier-louise-penthouse-contemporain-avec-2-terrasses\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/www.immopeople.be\/nl\/a-vendre\/quartier-louise-penthouse-contemporain-avec-2-terrasses\/#primaryimage\",\"url\":\"https:\/\/www.immopeople.be\/wp-content\/uploads\/2026\/05\/image00010-3.jpeg\",\"contentUrl\":\"https:\/\/www.immopeople.be\/wp-content\/uploads\/2026\/05\/image00010-3.jpeg\",\"width\":1920,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.immopeople.be\/nl\/a-vendre\/quartier-louise-penthouse-contemporain-avec-2-terrasses\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.immopeople.be\/nl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c0 vendre\",\"item\":\"https:\/\/www.immopeople.be\/nl\/a-vendre\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Quartier Louise &#8211; Penthouse contemporain avec 2 terrasses\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.immopeople.be\/nl\/#website\",\"url\":\"https:\/\/www.immopeople.be\/nl\/\",\"name\":\"Immo People\",\"description\":\"Trouvez la maison de vos r\u00eaves\",\"publisher\":{\"@id\":\"https:\/\/www.immopeople.be\/nl\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.immopeople.be\/nl\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.immopeople.be\/nl\/#organization\",\"name\":\"Immo People\",\"url\":\"https:\/\/www.immopeople.be\/nl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/www.immopeople.be\/nl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.immopeople.be\/wp-content\/uploads\/2022\/10\/immo-people_BLEU.png\",\"contentUrl\":\"https:\/\/www.immopeople.be\/wp-content\/uploads\/2022\/10\/immo-people_BLEU.png\",\"width\":2818,\"height\":1731,\"caption\":\"Immo People\"},\"image\":{\"@id\":\"https:\/\/www.immopeople.be\/nl\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/profile.php?id=100091200924603&locale=fr_FR\",\"https:\/\/www.instagram.com\/immo.people\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quartier Louise - Penthouse contemporain avec 2 terrasses - Immo People","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.immopeople.be\/nl\/a-vendre\/quartier-louise-penthouse-contemporain-avec-2-terrasses\/","og_locale":"nl_NL","og_type":"article","og_title":"Quartier Louise - Penthouse contemporain avec 2 terrasses - Immo People","og_url":"https:\/\/www.immopeople.be\/nl\/a-vendre\/quartier-louise-penthouse-contemporain-avec-2-terrasses\/","og_site_name":"Immo People","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100091200924603&locale=fr_FR","og_image":[{"width":1920,"height":1440,"url":"https:\/\/www.immopeople.be\/wp-content\/uploads\/2026\/05\/image00010-3.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Geschatte leestijd":"1 minuut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.immopeople.be\/nl\/a-vendre\/quartier-louise-penthouse-contemporain-avec-2-terrasses\/","url":"https:\/\/www.immopeople.be\/nl\/a-vendre\/quartier-louise-penthouse-contemporain-avec-2-terrasses\/","name":"Quartier Louise - Penthouse contemporain avec 2 terrasses - Immo People","isPartOf":{"@id":"https:\/\/www.immopeople.be\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.immopeople.be\/nl\/a-vendre\/quartier-louise-penthouse-contemporain-avec-2-terrasses\/#primaryimage"},"image":{"@id":"https:\/\/www.immopeople.be\/nl\/a-vendre\/quartier-louise-penthouse-contemporain-avec-2-terrasses\/#primaryimage"},"thumbnailUrl":"https:\/\/www.immopeople.be\/wp-content\/uploads\/2026\/05\/image00010-3.jpeg","datePublished":"2026-05-12T14:01:51+00:00","breadcrumb":{"@id":"https:\/\/www.immopeople.be\/nl\/a-vendre\/quartier-louise-penthouse-contemporain-avec-2-terrasses\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.immopeople.be\/nl\/a-vendre\/quartier-louise-penthouse-contemporain-avec-2-terrasses\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.immopeople.be\/nl\/a-vendre\/quartier-louise-penthouse-contemporain-avec-2-terrasses\/#primaryimage","url":"https:\/\/www.immopeople.be\/wp-content\/uploads\/2026\/05\/image00010-3.jpeg","contentUrl":"https:\/\/www.immopeople.be\/wp-content\/uploads\/2026\/05\/image00010-3.jpeg","width":1920,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/www.immopeople.be\/nl\/a-vendre\/quartier-louise-penthouse-contemporain-avec-2-terrasses\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.immopeople.be\/nl\/"},{"@type":"ListItem","position":2,"name":"\u00c0 vendre","item":"https:\/\/www.immopeople.be\/nl\/a-vendre\/"},{"@type":"ListItem","position":3,"name":"Quartier Louise &#8211; Penthouse contemporain avec 2 terrasses"}]},{"@type":"WebSite","@id":"https:\/\/www.immopeople.be\/nl\/#website","url":"https:\/\/www.immopeople.be\/nl\/","name":"Immo People","description":"Trouvez la maison de vos r\u00eaves","publisher":{"@id":"https:\/\/www.immopeople.be\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.immopeople.be\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/www.immopeople.be\/nl\/#organization","name":"Immo People","url":"https:\/\/www.immopeople.be\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.immopeople.be\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/www.immopeople.be\/wp-content\/uploads\/2022\/10\/immo-people_BLEU.png","contentUrl":"https:\/\/www.immopeople.be\/wp-content\/uploads\/2022\/10\/immo-people_BLEU.png","width":2818,"height":1731,"caption":"Immo People"},"image":{"@id":"https:\/\/www.immopeople.be\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100091200924603&locale=fr_FR","https:\/\/www.instagram.com\/immo.people\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.immopeople.be\/nl\/wp-json\/wp\/v2\/a-vendre\/5653","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.immopeople.be\/nl\/wp-json\/wp\/v2\/a-vendre"}],"about":[{"href":"https:\/\/www.immopeople.be\/nl\/wp-json\/wp\/v2\/types\/a-vendre"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.immopeople.be\/nl\/wp-json\/wp\/v2\/media\/5660"}],"wp:attachment":[{"href":"https:\/\/www.immopeople.be\/nl\/wp-json\/wp\/v2\/media?parent=5653"}],"wp:term":[{"taxonomy":"categorie-biens","embeddable":true,"href":"https:\/\/www.immopeople.be\/nl\/wp-json\/wp\/v2\/categorie-biens?post=5653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}